{"id":9376,"date":"2022-01-25T17:52:45","date_gmt":"2022-01-25T20:52:45","guid":{"rendered":"https:\/\/granpal.com.br\/site\/?p=9376"},"modified":"2022-11-17T10:48:40","modified_gmt":"2022-11-17T13:48:40","slug":"9376","status":"publish","type":"post","link":"https:\/\/www.granpal.com.br\/site\/sem-categoria\/9376\/","title":{"rendered":""},"content":{"rendered":"<p><span style=\"font-weight: 400;\">A estiagem no Rio Gravata\u00ed voltou ao debate nesta ter\u00e7a-feira (25), durante reuni\u00e3o entre prefeitos da Associa\u00e7\u00e3o dos Munic\u00edpios da Regi\u00e3o Metropolitana de Porto Alegre (Granpal) e o governador Eduardo Leite, no Pal\u00e1cio Piratini. Os gestores solicitaram agilidade na constru\u00e7\u00e3o de microbarragens no Rio Gravata\u00ed, a fim de auxiliar o abastecimento em \u00e9pocas de seca, como a sofrida pela regi\u00e3o neste momento. Tamb\u00e9m sugeriram a cria\u00e7\u00e3o de uma campanha de conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o para alertar sobre os riscos com o desperd\u00edcio de \u00e1gua.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O baixo n\u00edvel das bacias hidrogr\u00e1ficas, ocasionado pela falta de chuva e pelas altas temperaturas, pode ocasionar racionaliza\u00e7\u00e3o ou at\u00e9 falta de \u00e1gua em diversas cidades da Regi\u00e3o Metropolitana. O presidente da Granpal e prefeito de Porto Alegre, Sebasti\u00e3o Melo, defendeu um plano de curto, m\u00e9dio e longo prazo a ser seguido. A inten\u00e7\u00e3o \u00e9 evitar problemas de abastecimento nas comunidades. Melo lembrou que, desde a d\u00e9cada de 60, quando arrozeiros fizeram uma interven\u00e7\u00e3o no Gravata\u00ed para a irriga\u00e7\u00e3o das lavouras, a regi\u00e3o sofre com o problema de desabastecimento quando h\u00e1 per\u00edodos de estiagem. \u201cFoi um crime ambiental\u201d, argumentou o prefeito, destacando a import\u00e2ncia da efetiva\u00e7\u00e3o das microbarragens. Melo tamb\u00e9m solicitou ao governador a realiza\u00e7\u00e3o de uma campanha para o uso racional da \u00e1gua. \u201c\u00c9 preciso gastar o necess\u00e1rio\u201d, defendeu.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O prefeito de Gravata\u00ed, Luiz Zaffalon, recordou que a constru\u00e7\u00e3o de barragens \u00e9 um tema antigo. Ele tamb\u00e9m lembrou que o Rio Gravata\u00ed \u00e9 um importante manancial para o abastecimento de mais 500 mil pessoas. \u201cAs 13 microbarragens foram autorizadas pela Metroplan (Funda\u00e7\u00e3o Estadual de Planejamento Metropolitano e Regional), possuem recurso desde 2012, mas ainda depende da efetiva\u00e7\u00e3o do EIA-Rima para a posterior elabora\u00e7\u00e3o dos projetos de execu\u00e7\u00e3o\u201d explicou. Zaffalon tamb\u00e9m voltou a alertar que poder\u00e1 ser necess\u00e1rio o racionamento de \u00e1gua ou at\u00e9 o desabastecimento de v\u00e1rias cidades com a continuidade da falta de chuvas.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">O governador Eduardo Leite disse que o Executivo est\u00e1 comprometido com o tema e apresentou, por meio da Corsan, uma s\u00e9rie de medidas de curto e m\u00e9dio prazo que est\u00e3o sendo implementadas, como constru\u00e7\u00e3o de reservat\u00f3rios de \u00e1gua e substitui\u00e7\u00e3o de bombas. Tamb\u00e9m solicitou agilidade \u00e0 Metroplan no processo de efetiva\u00e7\u00e3o das microbarragens, bem como a elabora\u00e7\u00e3o de uma campanha de conscientiza\u00e7\u00e3o, envolvendo Defesa Civil e Corsan.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">A reuni\u00e3o tamb\u00e9m contou com as presen\u00e7as dos prefeitos de Cachoeirinha, Maur\u00edcio Medeiros; de Glorinha, Paulo Jos\u00e9 Silveira Corr\u00eaa; do chefe da Casa Civil, Artur Lemos; do secret\u00e1rio estadual de Desenvolvimento Urbano e Metropolitano, Luiz Carlos Busato; da secret\u00e1ria de Agricultura, Pecu\u00e1ria e Desenvolvimento Social, Silvana Covatti; do secret\u00e1rio-adjunto de Meio Ambiente, Guilherme de Souza; al\u00e9m de representante da Defesa Civil.\u00a0<\/span><\/p>\n<figure class=\"artigo__ilustracao\"><figcaption class=\"artigo__ilustracao__legenda\"><span class=\"artigo__ilustracao__credito\">Foto: Felipe Dalla Valle\/Pal\u00e1cio Piratini<\/span><\/figcaption><\/figure>\n<div class=\"artigo__texto\">\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A estiagem no Rio Gravata\u00ed voltou ao debate nesta ter\u00e7a-feira (25), durante reuni\u00e3o entre prefeitos da Associa\u00e7\u00e3o dos Munic\u00edpios da Regi\u00e3o Metropolitana de Porto Alegre (Granpal) e o governador Eduardo Leite, no Pal\u00e1cio Piratini. Os gestores solicitaram agilidade na constru\u00e7\u00e3o de microbarragens no Rio Gravata\u00ed, a fim de auxiliar o abastecimento em \u00e9pocas de seca, como a sofrida pela regi\u00e3o neste momento. Tamb\u00e9m sugeriram a cria\u00e7\u00e3o de uma campanha de conscientiza\u00e7\u00e3o da popula\u00e7\u00e3o para alertar sobre os riscos com o desperd\u00edcio de \u00e1gua. O baixo n\u00edvel das bacias hidrogr\u00e1ficas, ocasionado pela falta de chuva e pelas altas temperaturas, pode ocasionar racionaliza\u00e7\u00e3o ou at\u00e9 falta de \u00e1gua em diversas cidades da Regi\u00e3o Metropolitana. O presidente da Granpal e prefeito de Porto Alegre, Sebasti\u00e3o Melo, defendeu um plano de curto, m\u00e9dio e longo prazo a ser seguido. A inten\u00e7\u00e3o \u00e9 evitar problemas de abastecimento nas comunidades. Melo lembrou que, desde a d\u00e9cada de 60, quando arrozeiros fizeram uma interven\u00e7\u00e3o no Gravata\u00ed para a irriga\u00e7\u00e3o das lavouras, a regi\u00e3o sofre com o problema de desabastecimento quando h\u00e1 per\u00edodos de estiagem. \u201cFoi um crime ambiental\u201d, argumentou o prefeito, destacando a import\u00e2ncia da efetiva\u00e7\u00e3o das microbarragens. Melo tamb\u00e9m solicitou ao governador a realiza\u00e7\u00e3o de uma campanha para o uso racional da \u00e1gua. \u201c\u00c9 preciso gastar o necess\u00e1rio\u201d, defendeu. O prefeito de Gravata\u00ed, Luiz Zaffalon, recordou que a constru\u00e7\u00e3o de barragens \u00e9 um tema antigo. Ele tamb\u00e9m lembrou que o Rio Gravata\u00ed \u00e9 um importante manancial para o abastecimento de mais 500 mil pessoas. \u201cAs 13 microbarragens foram autorizadas pela Metroplan (Funda\u00e7\u00e3o Estadual de Planejamento Metropolitano e Regional), possuem recurso desde 2012, mas ainda depende da efetiva\u00e7\u00e3o do EIA-Rima para a posterior elabora\u00e7\u00e3o dos projetos de execu\u00e7\u00e3o\u201d explicou. Zaffalon tamb\u00e9m voltou a alertar que poder\u00e1 ser necess\u00e1rio o racionamento de \u00e1gua ou at\u00e9 o desabastecimento de v\u00e1rias cidades com a continuidade da falta de chuvas. O governador Eduardo Leite disse que o Executivo est\u00e1 comprometido com o tema e apresentou, por meio da Corsan, uma s\u00e9rie de medidas de curto e m\u00e9dio prazo que est\u00e3o sendo implementadas, como constru\u00e7\u00e3o de reservat\u00f3rios de \u00e1gua e substitui\u00e7\u00e3o de bombas. Tamb\u00e9m solicitou agilidade \u00e0 Metroplan no processo de efetiva\u00e7\u00e3o das microbarragens, bem como a elabora\u00e7\u00e3o de uma campanha de conscientiza\u00e7\u00e3o, envolvendo Defesa Civil e Corsan.\u00a0 A reuni\u00e3o tamb\u00e9m contou com as presen\u00e7as dos prefeitos de Cachoeirinha, Maur\u00edcio Medeiros; de Glorinha, Paulo Jos\u00e9 Silveira Corr\u00eaa; do chefe da Casa Civil, Artur Lemos; do secret\u00e1rio estadual de Desenvolvimento Urbano e Metropolitano, Luiz Carlos Busato; da secret\u00e1ria de Agricultura, Pecu\u00e1ria e Desenvolvimento Social, Silvana Covatti; do secret\u00e1rio-adjunto de Meio Ambiente, Guilherme de Souza; al\u00e9m de representante da Defesa Civil.\u00a0 Foto: Felipe Dalla Valle\/Pal\u00e1cio Piratini<\/p>\n","protected":false},"author":1,"featured_media":9377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[53,1],"tags":[],"class_list":["post-9376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-granpal","category-sem-categoria"],"_links":{"self":[{"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/posts\/9376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/comments?post=9376"}],"version-history":[{"count":1,"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/posts\/9376\/revisions"}],"predecessor-version":[{"id":9663,"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/posts\/9376\/revisions\/9663"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/media?parent=9376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/categories?post=9376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granpal.com.br\/site\/wp-json\/wp\/v2\/tags?post=9376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}